{"id":8178,"date":"2025-03-09T03:37:04","date_gmt":"2025-03-09T02:37:04","guid":{"rendered":"https:\/\/axanabellard.com\/?p=8178"},"modified":"2025-04-02T22:38:08","modified_gmt":"2025-04-02T20:38:08","slug":"sa-vision-sur-la-crise-actuelle","status":"publish","type":"post","link":"https:\/\/axanabellard.org\/en\/sa-vision-sur-la-crise-actuelle\/","title":{"rendered":"Sa vision sur la crise actuelle"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8178\" class=\"elementor elementor-8178\">\n\t\t\t\t<div class=\"elementor-element elementor-element-155f575a e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"155f575a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fb08361 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-parent\" data-id=\"5fb08361\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-11862c57 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no e-con e-child\" data-id=\"11862c57\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e799a5b elementor-widget elementor-widget-heading\" data-id=\"e799a5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Sa vision sur la crise actuelle\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ec0d67e elementor-widget elementor-widget-stm_post_about_author\" data-id=\"1ec0d67e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"stm_post_about_author.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"about_author_wr  consulting_elementor_post_about_author\">\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-484d8d8b wpr-post-info-align-left elementor-widget elementor-widget-wpr-post-info\" data-id=\"484d8d8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"wpr-post-info wpr-post-info-vertical\"><li class=\"wpr-post-info-taxonomy\"><span>Articles<span class=\"tax-sep\">, <\/span><\/span><span>Fran\u00e7ais<\/span><\/li><li class=\"wpr-post-info-date\"><span>9 March 2025<\/span><\/li><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4ad32d elementor-widget elementor-widget-text-editor\" data-id=\"e4ad32d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wp-block-group\">\n<p><\/p>\n<p class=\"has-text-align-left\">Selon sa vision de la gouvernance, Monsieur Abellard con\u00e7oit la gestion de l\u2019\u00c9tat\u00a0de mani\u00e8re juste, s\u00e9curis\u00e9e et \u00e9galitaire en tenant compte des divergences sociales persistantes. Il estime qu&rsquo;il revient \u00e0 l\u2019\u00c9tat de r\u00e9tablir l\u2019ordre en cr\u00e9ant des opportunit\u00e9s pour tous et toutes. \u00c9voluant dans le secteur des affaires, il a contribu\u00e9 \u00e0 la cr\u00e9ation de nombreux emplois dans le pays \u00e0 travers sa firme de consultation en ing\u00e9nierie, <strong>CECOM CONSULTANTS SA<\/strong> existant depuis trente-sept (37) ans. C\u2019est de cette exp\u00e9rience v\u00e9cue sur le terrain qu\u2019a \u00e9merg\u00e9 sa d\u00e9votion pour la gestion de l\u2019\u00c9tat. Bien qu&rsquo;il n&rsquo;ait jamais occup\u00e9 de poste politique, il met en avant ses r\u00e9alisations dans le domaine social.<\/p>\n<p>\u00a0<\/p>\n<p><\/p>\n<p class=\"has-text-align-left\">Concernant sa perception de la situation actuelle du pays, il consid\u00e8re que la lutte contre l\u2019ins\u00e9curit\u00e9 constitue une priorit\u00e9. \u00c0 cet effet, il est pour l\u2019adoption de la <strong>Doctrine de la <em>force \u00e9crasante<\/em><\/strong>. Ensuite, il pr\u00f4ne la cr\u00e9ation d\u2019emplois par l\u2019industrialisation financ\u00e9e par les investissements nationaux, internationaux et de la diaspora dans trois p\u00f4les r\u00e9gionaux (Nord, Centre et Sud) de d\u00e9veloppement \u00e9conomique. Puis, il pr\u00e9conise un accroissement consid\u00e9rable du budget national par l\u2019augmentation de la pression fiscale ce dans le but de relancer l\u2019\u00e9conomie de la R\u00e9publique. Selon lui, l\u2019\u00e9thique et la justice sociale doivent \u00eatre les principes fondamentaux guidant l\u2019action publique.\u00a0<\/p>\n<p>\u00a0<\/p>\n<p class=\"has-text-align-left\">Sans d\u00e9tour, Monsieur Abellard qualifie de mauvaise depuis des d\u00e9cennies la gestion du pays. Il plaide pour la fin de cette gouvernance traditionnelle domin\u00e9e par des fonctionnaires et des dirigeants politiques incomp\u00e9tents, irresponsables et corrompus pour la plupart. En ce qui concerne la conciliation entre croissance \u00e9conomique et justice sociale, il promeut la mise en place de programmes d\u2019aide sociaux destin\u00e9s aux plus d\u00e9munis. Il propose, \u00e0 cet effet de restructurer le syst\u00e8me fiscal pour le rendre plus \u00e9quitable. Sur le plan \u00e9ducatif, il d\u00e9fend une r\u00e9forme visant \u00e0 favoriser une \u00e9ducation adapt\u00e9e aux r\u00e9alit\u00e9s du pays ainsi que des formations techniques de courte dur\u00e9e.<\/p>\n<p>\u00a0<\/p>\n<p><\/p>\n<p class=\"has-text-align-left\">Par ailleurs, Monsieur Abellard insiste sur la n\u00e9cessit\u00e9 pour l\u2019\u00c9tat de reconstituer les organismes de lutte contre la corruption, en leur accordant davantage de pouvoir et d\u2019autonomie. Il sugg\u00e8re \u00e9galement de donner le pouvoir de police judiciaire et d\u2019interpellation aux agents sp\u00e9cialis\u00e9s de l\u2019ULCC pour renforcer la loi dans ce domaine en synergie avec d\u2019autres institutions.<\/p>\n<p>\u00a0<\/p>\n<p><\/p>\n<p class=\"has-text-align-left\">Partisan de l\u2019\u00e9galit\u00e9 des genres, il opte pour une r\u00e9partition \u00e9quitable du pouvoir. Nomm\u00e9 \u00e0 la t\u00eate du gouvernement, ses cent (100) premiers jours de mandat seraient consacr\u00e9s prioritairement \u00e0 la s\u00e9curit\u00e9 nationale. Il mettrait en \u0153uvre son agenda pour le r\u00e9tablissement de l\u2019ordre. Il formerait des milliers de jeunes patriotes combattants et d\u00e9dirait trente-cinq (35%) du budget officiel \u00e0 un fonds consacr\u00e9 exclusivement \u00e0 l\u2019\u00e9radication de la criminalit\u00e9.<\/p>\n<p>\u00a0<\/p>\n<p><\/p>\n<p class=\"has-text-align-left\">En somme, le Citoyen Axan Abellard propose une gouvernance de l\u2019\u00c9tat ax\u00e9e sur la s\u00e9curit\u00e9, la justice sociale et la croissance \u00e9conomique. Il encourage une gestion de l\u2019\u00c9tat fond\u00e9e sur l\u2019\u00e9thique, la transparence et l\u2019efficacit\u00e9. Il insiste sur la n\u00e9cessit\u00e9 d\u2019une refonte profonde des institutions, notamment du syst\u00e8me \u00e9ducatif et fiscal. De par ses convictions, il aspire \u00e0 un \u00c9tat fort, capable de garantir la stabilit\u00e9 et le bien-\u00eatre de tous les citoyens.<\/p>\n<p><\/p>\n<\/div>\n<p><!-- \/wp:group --><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sa vision sur la crise actuelle Articles, Fran\u00e7ais 9 mars 2025 Selon sa vision de la gouvernance, Monsieur Abellard con\u00e7oit la gestion de l\u2019\u00c9tat\u00a0de mani\u00e8re juste, s\u00e9curis\u00e9e et \u00e9galitaire en tenant compte des divergences sociales persistantes. Il estime qu&rsquo;il revient \u00e0 l\u2019\u00c9tat de r\u00e9tablir l\u2019ordre en cr\u00e9ant des opportunit\u00e9s pour tous et toutes. \u00c9voluant dans le secteur des affaires, il a contribu\u00e9 \u00e0 la cr\u00e9ation de nombreux emplois dans le pays \u00e0 travers sa firme de consultation en ing\u00e9nierie, CECOM CONSULTANTS SA existant depuis trente-sept (37) ans. C\u2019est de cette exp\u00e9rience v\u00e9cue sur le terrain qu\u2019a \u00e9merg\u00e9 sa d\u00e9votion pour la gestion de l\u2019\u00c9tat. Bien qu&rsquo;il n&rsquo;ait jamais occup\u00e9 de poste politique, il met en avant ses r\u00e9alisations dans le domaine social. \u00a0 Concernant sa perception de la situation actuelle du pays, il consid\u00e8re que la lutte contre l\u2019ins\u00e9curit\u00e9 constitue une priorit\u00e9. \u00c0 cet effet, il est pour l\u2019adoption de la Doctrine de la force \u00e9crasante. Ensuite, il pr\u00f4ne la cr\u00e9ation d\u2019emplois par l\u2019industrialisation financ\u00e9e par les investissements nationaux, internationaux et de la diaspora dans trois p\u00f4les r\u00e9gionaux (Nord, Centre et Sud) de d\u00e9veloppement \u00e9conomique. Puis, il pr\u00e9conise un accroissement consid\u00e9rable du budget national par l\u2019augmentation de la pression fiscale ce dans le but de relancer l\u2019\u00e9conomie de la R\u00e9publique. Selon lui, l\u2019\u00e9thique et la justice sociale doivent \u00eatre les principes fondamentaux guidant l\u2019action publique.\u00a0 \u00a0 Sans d\u00e9tour, Monsieur Abellard qualifie de mauvaise depuis des d\u00e9cennies la gestion du pays. Il plaide pour la fin de cette gouvernance traditionnelle domin\u00e9e par des fonctionnaires et des dirigeants politiques incomp\u00e9tents, irresponsables et corrompus pour la plupart. En ce qui concerne la conciliation entre croissance \u00e9conomique et justice sociale, il promeut la mise en place de programmes d\u2019aide sociaux destin\u00e9s aux plus d\u00e9munis. Il propose, \u00e0 cet effet de restructurer le syst\u00e8me fiscal pour le rendre plus \u00e9quitable. Sur le plan \u00e9ducatif, il d\u00e9fend une r\u00e9forme visant \u00e0 favoriser une \u00e9ducation adapt\u00e9e aux r\u00e9alit\u00e9s du pays ainsi que des formations techniques de courte dur\u00e9e. \u00a0 Par ailleurs, Monsieur Abellard insiste sur la n\u00e9cessit\u00e9 pour l\u2019\u00c9tat de reconstituer les organismes de lutte contre la corruption, en leur accordant davantage de pouvoir et d\u2019autonomie. Il sugg\u00e8re \u00e9galement de donner le pouvoir de police judiciaire et d\u2019interpellation aux agents sp\u00e9cialis\u00e9s de l\u2019ULCC pour renforcer la loi dans ce domaine en synergie avec d\u2019autres institutions. \u00a0 Partisan de l\u2019\u00e9galit\u00e9 des genres, il opte pour une r\u00e9partition \u00e9quitable du pouvoir. Nomm\u00e9 \u00e0 la t\u00eate du gouvernement, ses cent (100) premiers jours de mandat seraient consacr\u00e9s prioritairement \u00e0 la s\u00e9curit\u00e9 nationale. Il mettrait en \u0153uvre son agenda pour le r\u00e9tablissement de l\u2019ordre. Il formerait des milliers de jeunes patriotes combattants et d\u00e9dirait trente-cinq (35%) du budget officiel \u00e0 un fonds consacr\u00e9 exclusivement \u00e0 l\u2019\u00e9radication de la criminalit\u00e9. \u00a0 En somme, le Citoyen Axan Abellard propose une gouvernance de l\u2019\u00c9tat ax\u00e9e sur la s\u00e9curit\u00e9, la justice sociale et la croissance \u00e9conomique. Il encourage une gestion de l\u2019\u00c9tat fond\u00e9e sur l\u2019\u00e9thique, la transparence et l\u2019efficacit\u00e9. Il insiste sur la n\u00e9cessit\u00e9 d\u2019une refonte profonde des institutions, notamment du syst\u00e8me \u00e9ducatif et fiscal. De par ses convictions, il aspire \u00e0 un \u00c9tat fort, capable de garantir la stabilit\u00e9 et le bien-\u00eatre de tous les citoyens.<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[111,110],"tags":[],"class_list":["post-8178","post","type-post","status-publish","format-standard","hentry","category-articles","category-francais"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sa vision sur la crise actuelle - Axan Abellard<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/axanabellard.org\/en\/sa-vision-sur-la-crise-actuelle\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sa vision sur la crise actuelle - Axan Abellard\" \/>\n<meta property=\"og:description\" content=\"Sa vision sur la crise actuelle Articles, Fran\u00e7ais 9 mars 2025 Selon sa vision de la gouvernance, Monsieur Abellard con\u00e7oit la gestion de l\u2019\u00c9tat\u00a0de mani\u00e8re juste, s\u00e9curis\u00e9e et \u00e9galitaire en tenant compte des divergences sociales persistantes. Il estime qu&rsquo;il revient \u00e0 l\u2019\u00c9tat de r\u00e9tablir l\u2019ordre en cr\u00e9ant des opportunit\u00e9s pour tous et toutes. \u00c9voluant dans le secteur des affaires, il a contribu\u00e9 \u00e0 la cr\u00e9ation de nombreux emplois dans le pays \u00e0 travers sa firme de consultation en ing\u00e9nierie, CECOM CONSULTANTS SA existant depuis trente-sept (37) ans. C\u2019est de cette exp\u00e9rience v\u00e9cue sur le terrain qu\u2019a \u00e9merg\u00e9 sa d\u00e9votion pour la gestion de l\u2019\u00c9tat. Bien qu&rsquo;il n&rsquo;ait jamais occup\u00e9 de poste politique, il met en avant ses r\u00e9alisations dans le domaine social. \u00a0 Concernant sa perception de la situation actuelle du pays, il consid\u00e8re que la lutte contre l\u2019ins\u00e9curit\u00e9 constitue une priorit\u00e9. \u00c0 cet effet, il est pour l\u2019adoption de la Doctrine de la force \u00e9crasante. Ensuite, il pr\u00f4ne la cr\u00e9ation d\u2019emplois par l\u2019industrialisation financ\u00e9e par les investissements nationaux, internationaux et de la diaspora dans trois p\u00f4les r\u00e9gionaux (Nord, Centre et Sud) de d\u00e9veloppement \u00e9conomique. Puis, il pr\u00e9conise un accroissement consid\u00e9rable du budget national par l\u2019augmentation de la pression fiscale ce dans le but de relancer l\u2019\u00e9conomie de la R\u00e9publique. Selon lui, l\u2019\u00e9thique et la justice sociale doivent \u00eatre les principes fondamentaux guidant l\u2019action publique.\u00a0 \u00a0 Sans d\u00e9tour, Monsieur Abellard qualifie de mauvaise depuis des d\u00e9cennies la gestion du pays. Il plaide pour la fin de cette gouvernance traditionnelle domin\u00e9e par des fonctionnaires et des dirigeants politiques incomp\u00e9tents, irresponsables et corrompus pour la plupart. En ce qui concerne la conciliation entre croissance \u00e9conomique et justice sociale, il promeut la mise en place de programmes d\u2019aide sociaux destin\u00e9s aux plus d\u00e9munis. Il propose, \u00e0 cet effet de restructurer le syst\u00e8me fiscal pour le rendre plus \u00e9quitable. Sur le plan \u00e9ducatif, il d\u00e9fend une r\u00e9forme visant \u00e0 favoriser une \u00e9ducation adapt\u00e9e aux r\u00e9alit\u00e9s du pays ainsi que des formations techniques de courte dur\u00e9e. \u00a0 Par ailleurs, Monsieur Abellard insiste sur la n\u00e9cessit\u00e9 pour l\u2019\u00c9tat de reconstituer les organismes de lutte contre la corruption, en leur accordant davantage de pouvoir et d\u2019autonomie. Il sugg\u00e8re \u00e9galement de donner le pouvoir de police judiciaire et d\u2019interpellation aux agents sp\u00e9cialis\u00e9s de l\u2019ULCC pour renforcer la loi dans ce domaine en synergie avec d\u2019autres institutions. \u00a0 Partisan de l\u2019\u00e9galit\u00e9 des genres, il opte pour une r\u00e9partition \u00e9quitable du pouvoir. Nomm\u00e9 \u00e0 la t\u00eate du gouvernement, ses cent (100) premiers jours de mandat seraient consacr\u00e9s prioritairement \u00e0 la s\u00e9curit\u00e9 nationale. Il mettrait en \u0153uvre son agenda pour le r\u00e9tablissement de l\u2019ordre. Il formerait des milliers de jeunes patriotes combattants et d\u00e9dirait trente-cinq (35%) du budget officiel \u00e0 un fonds consacr\u00e9 exclusivement \u00e0 l\u2019\u00e9radication de la criminalit\u00e9. \u00a0 En somme, le Citoyen Axan Abellard propose une gouvernance de l\u2019\u00c9tat ax\u00e9e sur la s\u00e9curit\u00e9, la justice sociale et la croissance \u00e9conomique. Il encourage une gestion de l\u2019\u00c9tat fond\u00e9e sur l\u2019\u00e9thique, la transparence et l\u2019efficacit\u00e9. Il insiste sur la n\u00e9cessit\u00e9 d\u2019une refonte profonde des institutions, notamment du syst\u00e8me \u00e9ducatif et fiscal. De par ses convictions, il aspire \u00e0 un \u00c9tat fort, capable de garantir la stabilit\u00e9 et le bien-\u00eatre de tous les citoyens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/axanabellard.org\/en\/sa-vision-sur-la-crise-actuelle\/\" \/>\n<meta property=\"og:site_name\" content=\"Axan Abellard\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1BcfYNKqV4\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-09T02:37:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T20:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/axanabellard.org\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-a-09.18.49_20267870.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@abellard_axan\" \/>\n<meta name=\"twitter:site\" content=\"@abellard_axan\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#\\\/schema\\\/person\\\/d7837d6e3b4878feacda308ef3598c46\"},\"headline\":\"Sa vision sur la crise actuelle\",\"datePublished\":\"2025-03-09T02:37:04+00:00\",\"dateModified\":\"2025-04-02T20:38:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/\"},\"wordCount\":603,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#organization\"},\"articleSection\":[\"Articles\",\"Fran\u00e7ais\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/\",\"url\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/\",\"name\":\"Sa vision sur la crise actuelle - Axan Abellard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#website\"},\"datePublished\":\"2025-03-09T02:37:04+00:00\",\"dateModified\":\"2025-04-02T20:38:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/sa-vision-sur-la-crise-actuelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/axanabellard.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sa vision sur la crise actuelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#website\",\"url\":\"https:\\\/\\\/axanabellard.org\\\/\",\"name\":\"Axan Abellard\",\"description\":\"Cessons l&#039;anarchie aujoud&#039;hui me\u0302me\",\"publisher\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axanabellard.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#organization\",\"name\":\"Axan Abellard\",\"url\":\"https:\\\/\\\/axanabellard.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/axanabellard.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-24-a-09.18.49_20267870.jpg\",\"contentUrl\":\"https:\\\/\\\/axanabellard.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/WhatsApp-Image-2025-02-24-a-09.18.49_20267870.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Axan Abellard\"},\"image\":{\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/1BcfYNKqV4\\\/\",\"https:\\\/\\\/x.com\\\/abellard_axan\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/axanabellard.org\\\/#\\\/schema\\\/person\\\/d7837d6e3b4878feacda308ef3598c46\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dd587fe00d05e5b9f7c68d3304e33b846722a1fc6a5c934ae063735614c11be?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dd587fe00d05e5b9f7c68d3304e33b846722a1fc6a5c934ae063735614c11be?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7dd587fe00d05e5b9f7c68d3304e33b846722a1fc6a5c934ae063735614c11be?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/axanabellard.org\"],\"url\":\"https:\\\/\\\/axanabellard.org\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sa vision sur la crise actuelle - Axan Abellard","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/axanabellard.org\/en\/sa-vision-sur-la-crise-actuelle\/","og_locale":"en_US","og_type":"article","og_title":"Sa vision sur la crise actuelle - Axan Abellard","og_description":"Sa vision sur la crise actuelle Articles, Fran\u00e7ais 9 mars 2025 Selon sa vision de la gouvernance, Monsieur Abellard con\u00e7oit la gestion de l\u2019\u00c9tat\u00a0de mani\u00e8re juste, s\u00e9curis\u00e9e et \u00e9galitaire en tenant compte des divergences sociales persistantes. Il estime qu&rsquo;il revient \u00e0 l\u2019\u00c9tat de r\u00e9tablir l\u2019ordre en cr\u00e9ant des opportunit\u00e9s pour tous et toutes. \u00c9voluant dans le secteur des affaires, il a contribu\u00e9 \u00e0 la cr\u00e9ation de nombreux emplois dans le pays \u00e0 travers sa firme de consultation en ing\u00e9nierie, CECOM CONSULTANTS SA existant depuis trente-sept (37) ans. C\u2019est de cette exp\u00e9rience v\u00e9cue sur le terrain qu\u2019a \u00e9merg\u00e9 sa d\u00e9votion pour la gestion de l\u2019\u00c9tat. Bien qu&rsquo;il n&rsquo;ait jamais occup\u00e9 de poste politique, il met en avant ses r\u00e9alisations dans le domaine social. \u00a0 Concernant sa perception de la situation actuelle du pays, il consid\u00e8re que la lutte contre l\u2019ins\u00e9curit\u00e9 constitue une priorit\u00e9. \u00c0 cet effet, il est pour l\u2019adoption de la Doctrine de la force \u00e9crasante. Ensuite, il pr\u00f4ne la cr\u00e9ation d\u2019emplois par l\u2019industrialisation financ\u00e9e par les investissements nationaux, internationaux et de la diaspora dans trois p\u00f4les r\u00e9gionaux (Nord, Centre et Sud) de d\u00e9veloppement \u00e9conomique. Puis, il pr\u00e9conise un accroissement consid\u00e9rable du budget national par l\u2019augmentation de la pression fiscale ce dans le but de relancer l\u2019\u00e9conomie de la R\u00e9publique. Selon lui, l\u2019\u00e9thique et la justice sociale doivent \u00eatre les principes fondamentaux guidant l\u2019action publique.\u00a0 \u00a0 Sans d\u00e9tour, Monsieur Abellard qualifie de mauvaise depuis des d\u00e9cennies la gestion du pays. Il plaide pour la fin de cette gouvernance traditionnelle domin\u00e9e par des fonctionnaires et des dirigeants politiques incomp\u00e9tents, irresponsables et corrompus pour la plupart. En ce qui concerne la conciliation entre croissance \u00e9conomique et justice sociale, il promeut la mise en place de programmes d\u2019aide sociaux destin\u00e9s aux plus d\u00e9munis. Il propose, \u00e0 cet effet de restructurer le syst\u00e8me fiscal pour le rendre plus \u00e9quitable. Sur le plan \u00e9ducatif, il d\u00e9fend une r\u00e9forme visant \u00e0 favoriser une \u00e9ducation adapt\u00e9e aux r\u00e9alit\u00e9s du pays ainsi que des formations techniques de courte dur\u00e9e. \u00a0 Par ailleurs, Monsieur Abellard insiste sur la n\u00e9cessit\u00e9 pour l\u2019\u00c9tat de reconstituer les organismes de lutte contre la corruption, en leur accordant davantage de pouvoir et d\u2019autonomie. Il sugg\u00e8re \u00e9galement de donner le pouvoir de police judiciaire et d\u2019interpellation aux agents sp\u00e9cialis\u00e9s de l\u2019ULCC pour renforcer la loi dans ce domaine en synergie avec d\u2019autres institutions. \u00a0 Partisan de l\u2019\u00e9galit\u00e9 des genres, il opte pour une r\u00e9partition \u00e9quitable du pouvoir. Nomm\u00e9 \u00e0 la t\u00eate du gouvernement, ses cent (100) premiers jours de mandat seraient consacr\u00e9s prioritairement \u00e0 la s\u00e9curit\u00e9 nationale. Il mettrait en \u0153uvre son agenda pour le r\u00e9tablissement de l\u2019ordre. Il formerait des milliers de jeunes patriotes combattants et d\u00e9dirait trente-cinq (35%) du budget officiel \u00e0 un fonds consacr\u00e9 exclusivement \u00e0 l\u2019\u00e9radication de la criminalit\u00e9. \u00a0 En somme, le Citoyen Axan Abellard propose une gouvernance de l\u2019\u00c9tat ax\u00e9e sur la s\u00e9curit\u00e9, la justice sociale et la croissance \u00e9conomique. Il encourage une gestion de l\u2019\u00c9tat fond\u00e9e sur l\u2019\u00e9thique, la transparence et l\u2019efficacit\u00e9. Il insiste sur la n\u00e9cessit\u00e9 d\u2019une refonte profonde des institutions, notamment du syst\u00e8me \u00e9ducatif et fiscal. De par ses convictions, il aspire \u00e0 un \u00c9tat fort, capable de garantir la stabilit\u00e9 et le bien-\u00eatre de tous les citoyens.","og_url":"https:\/\/axanabellard.org\/en\/sa-vision-sur-la-crise-actuelle\/","og_site_name":"Axan Abellard","article_publisher":"https:\/\/www.facebook.com\/share\/1BcfYNKqV4\/","article_published_time":"2025-03-09T02:37:04+00:00","article_modified_time":"2025-04-02T20:38:08+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/axanabellard.org\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-a-09.18.49_20267870.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@abellard_axan","twitter_site":"@abellard_axan","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/#article","isPartOf":{"@id":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/"},"author":{"name":"admin","@id":"https:\/\/axanabellard.org\/#\/schema\/person\/d7837d6e3b4878feacda308ef3598c46"},"headline":"Sa vision sur la crise actuelle","datePublished":"2025-03-09T02:37:04+00:00","dateModified":"2025-04-02T20:38:08+00:00","mainEntityOfPage":{"@id":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/"},"wordCount":603,"commentCount":0,"publisher":{"@id":"https:\/\/axanabellard.org\/#organization"},"articleSection":["Articles","Fran\u00e7ais"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/","url":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/","name":"Sa vision sur la crise actuelle - Axan Abellard","isPartOf":{"@id":"https:\/\/axanabellard.org\/#website"},"datePublished":"2025-03-09T02:37:04+00:00","dateModified":"2025-04-02T20:38:08+00:00","breadcrumb":{"@id":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/axanabellard.org\/sa-vision-sur-la-crise-actuelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/axanabellard.org\/"},{"@type":"ListItem","position":2,"name":"Sa vision sur la crise actuelle"}]},{"@type":"WebSite","@id":"https:\/\/axanabellard.org\/#website","url":"https:\/\/axanabellard.org\/","name":"Axan Abellard","description":"Cessons l&#039;anarchie aujoud&#039;hui me\u0302me","publisher":{"@id":"https:\/\/axanabellard.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axanabellard.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/axanabellard.org\/#organization","name":"Axan Abellard","url":"https:\/\/axanabellard.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/axanabellard.org\/#\/schema\/logo\/image\/","url":"https:\/\/axanabellard.org\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-a-09.18.49_20267870.jpg","contentUrl":"https:\/\/axanabellard.org\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-24-a-09.18.49_20267870.jpg","width":1280,"height":853,"caption":"Axan Abellard"},"image":{"@id":"https:\/\/axanabellard.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1BcfYNKqV4\/","https:\/\/x.com\/abellard_axan"]},{"@type":"Person","@id":"https:\/\/axanabellard.org\/#\/schema\/person\/d7837d6e3b4878feacda308ef3598c46","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7dd587fe00d05e5b9f7c68d3304e33b846722a1fc6a5c934ae063735614c11be?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7dd587fe00d05e5b9f7c68d3304e33b846722a1fc6a5c934ae063735614c11be?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7dd587fe00d05e5b9f7c68d3304e33b846722a1fc6a5c934ae063735614c11be?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/axanabellard.org"],"url":"https:\/\/axanabellard.org\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/posts\/8178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/comments?post=8178"}],"version-history":[{"count":61,"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/posts\/8178\/revisions"}],"predecessor-version":[{"id":10525,"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/posts\/8178\/revisions\/10525"}],"wp:attachment":[{"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/media?parent=8178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/categories?post=8178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/axanabellard.org\/en\/wp-json\/wp\/v2\/tags?post=8178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}